{"id":25,"date":"2023-09-17T14:26:31","date_gmt":"2023-09-17T14:26:31","guid":{"rendered":"https:\/\/biolabverse.com\/?page_id=25"},"modified":"2023-11-13T15:12:24","modified_gmt":"2023-11-13T15:12:24","slug":"home","status":"publish","type":"page","link":"https:\/\/biolabverse.com\/index.php\/home\/","title":{"rendered":"Home"},"content":{"rendered":"\n<pre class=\"wp-block-verse\"><strong>Dhananjay Dasiram Jade<\/strong><\/pre>\n\n\n\n<p>PhD Scholar<\/p>\n\n\n\n<p>PhD Student at University of Leeds<\/p>\n\n\n\n<div class=\"wp-block-cover alignwide is-light wp-duotone-ffffff-ffffff-2\" style=\"min-height:452px\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-layout-1 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-layout-1 wp-block-group-is-layout-flex\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.researchgate.net\/profile\/Dhananjay-Jade\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-1024x576.jpg\" alt=\"\" class=\"wp-image-131\" srcset=\"https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-1024x576.jpg 1024w, https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-300x169.jpg 300w, https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-768x432.jpg 768w, https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-1536x864.jpg 1536w, https:\/\/biolabverse.com\/wp-content\/uploads\/2023\/11\/PXL_20230406_085319161-2048x1152.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/figure>\n\n\n\n<blockquote class=\"wp-block-quote\">\n<figure class=\"wp-block-pullquote\"><blockquote><p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-picton-blue-color\">If we knew what it was we were doing, it would not be called research, would it?<\/mark><\/strong><\/p><\/blockquote><\/figure>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Dhananjay Dasiram Jade PhD Scholar PhD Student at University of Leeds<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/pages\/25"}],"collection":[{"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":14,"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":144,"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/pages\/25\/revisions\/144"}],"wp:attachment":[{"href":"https:\/\/biolabverse.com\/index.php\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}